{"id":978,"date":"2020-05-20T17:38:01","date_gmt":"2020-05-20T17:38:01","guid":{"rendered":"https:\/\/thecloud.group\/?page_id=978"},"modified":"2023-07-28T16:37:03","modified_gmt":"2023-07-28T16:37:03","slug":"profissionais-de-elearning","status":"publish","type":"page","link":"https:\/\/thecloud.group\/pt\/elearning-profesionales\/","title":{"rendered":"Profissionais de eLearning"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"978\" class=\"elementor elementor-978\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30da61ac elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"30da61ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66ee6c46\" data-id=\"66ee6c46\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-665a1ff3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"665a1ff3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b1a959d\" data-id=\"b1a959d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-78a3f947\" data-id=\"78a3f947\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4797b8 elementor-widget elementor-widget-heading\" data-id=\"e4797b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DISE\u00d1O DE E-LEARNINGS PROFESIONALES\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e6dd3 elementor-widget elementor-widget-heading\" data-id=\"e7e6dd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Con nuestros servicios de eLearning profesionales podr\u00e1s ofrecerle a tu equipo o a tus estudiantes un espacio para que se sigan formando a distancia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5d5b99 elementor-button-align-stretch elementor-widget elementor-widget-global elementor-global-12723 elementor-widget-form\" data-id=\"d5d5b99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;33&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"contactoR\u00e1pido\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"978\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"d5d5b99\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"The Cloud Group\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-telefono elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[telefono]\" id=\"form-field-telefono\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Tel\u00e9fono\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-field_79a04f2 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[field_79a04f2]\" id=\"form-field-field_79a04f2\" class=\"elementor-field elementor-size-xs  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-33 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\" id=\"fld_9272746\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SOLICITAR PRESUPUESTO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-277c93ae\" data-id=\"277c93ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fe9f233 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fe9f233\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-169027bf\" data-id=\"169027bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35e141b6 elementor-widget elementor-widget-heading\" data-id=\"35e141b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Clientes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6973e6a6 elementor-widget elementor-widget-global elementor-global-165 elementor-widget-image-carousel\" data-id=\"6973e6a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;1&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;10&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:80,&quot;sizes&quot;:[]},&quot;autoplay_speed&quot;:0,&quot;speed&quot;:50000,&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/09\/distrito.png\" alt=\"distrito\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/09\/vigoUniversity.png\" alt=\"vigoUniversity\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/metatrader-4-logo-og.png\" alt=\"metatrader-4-logo-og\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-TVE.webp\" alt=\"Dise\u00f1o sin t\u00edtulo TVE\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/fb_logo.png\" alt=\"fb_logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Iryo_2022_logo.png\" alt=\"Iryo_2022_logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Mercedes-Benz_Logo_2010.svg.png\" alt=\"Mercedes-Benz_Logo_2010.svg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/emirates-airlines-logo-01.png\" alt=\"emirates-airlines-logo-01\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/08\/servicios-expressos.png\" alt=\"servicios expressos\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-innermastery.webp\" alt=\"Dise\u00f1o sin t\u00edtulo innermastery\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-masterchef.webp\" alt=\"Dise\u00f1o sin t\u00edtulo masterchef\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/08\/MRW.png\" alt=\"MRW\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-merz.webp\" alt=\"Dise\u00f1o sin t\u00edtulo merz\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/real-madrid-png.webp\" alt=\"real madrid png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Guinea_Salud_logoverde_movil.png\" alt=\"Guinea_Salud_logoverde_movil\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/logo-nobackground-1000.png\" alt=\"logo-nobackground-1000\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/logo-secretaligner.png\" alt=\"logo-secretaligner\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Logo_Variante_FUNDACION_VF_03-1-scaled.png\" alt=\"Logo_Variante_FUNDACION_VF_03-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-legal.webp\" alt=\"Dise\u00f1o sin t\u00edtulo legal\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-nutco.webp\" alt=\"Dise\u00f1o sin t\u00edtulo nutco\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/GEPetrol.png\" alt=\"GEPetrol\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Marguisa-scaled.png\" alt=\"Marguisa\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Logo-Luria-Version-Azul-Oscuro-550x270px.png\" alt=\"Logo-Luria-Version-Azul-Oscuro-550x270px\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/zeta-studios-logo-983.png\" alt=\"zeta-studios-logo-983\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/8oQjFhUfCnt9qvXsjLF4DE.png\" alt=\"8oQjFhUfCnt9qvXsjLF4DE\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-png.webp\" alt=\"Dise\u00f1o sin t\u00edtulo png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/logo-1.png\" alt=\"logo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Cultural-Fit-Solutions-logo1_420x420.png\" alt=\"Cultural-Fit-Solutions-logo1_420x420\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/logo-besora.png\" alt=\"logo-besora\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo.png\" alt=\"Dise\u00f1o sin t\u00edtulo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/logo-marguisa.png\" alt=\"logo-marguisa\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/logo-hmm18755.png\" alt=\"logo-hmm18755\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-30-mar-2026-12_59_21.webp\" alt=\"ChatGPT Image 30 mar 2026, 12_59_21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-30-mar-2026-13_01_09.webp\" alt=\"ChatGPT Image 30 mar 2026, 13_01_09\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-30-mar-2026-13_02_55.webp\" alt=\"ChatGPT Image 30 mar 2026, 13_02_55\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-30-mar-2026-13_04_30.webp\" alt=\"ChatGPT Image 30 mar 2026, 13_04_30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-guinea.webp\" alt=\"Dise\u00f1o sin t\u00edtulo guinea\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2026\/08\/Camin-Europa.png\" alt=\"Camin Europa\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e22a365 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e22a365\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-50e751d9\" data-id=\"50e751d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26e94433 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"26e94433\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399662_Marketing.png\" class=\"attachment-full size-full wp-image-30\" alt=\"Con el Software ERP a Medida de The Cloud Group podr\u00e1s tener Estad\u00edsticas en Tiempo Real.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399662_Marketing.png 128w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399662_Marketing-66x66.png 66w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Capacitaci\u00f3n Flexible<\/h3><p class=\"elementor-image-box-description\">Nuestra empresa de desarrollo de software te ayudar\u00e1 a crear esa plataforma de eLearning para la ense\u00f1anza a distancia que tanto est\u00e1s buscando. A trav\u00e9s de estas herramientas podr\u00e1s ofrecer capacitaci\u00f3n de calidad de forma flexible y econ\u00f3mica de la cual se beneficiar\u00e1n tus alumnos y tu empresa.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7226f6ba elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"7226f6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399715_E-Commerce.png\" class=\"attachment-full size-full wp-image-32\" alt=\"Con el Software ERP a Medida de The Cloud Group obtendr\u00e1s un dise\u00f1o a medida.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399715_E-Commerce.png 128w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399715_E-Commerce-100x100.png 100w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399715_E-Commerce-66x66.png 66w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Anula Distancias<\/div><p class=\"elementor-image-box-description\">Las plataformas de eLearning profesionales anulan las distancias geogr\u00e1ficas y temporales ofreciendo opciones educativas accesibles a cualquier lugar donde haya una conexi\u00f3n a internet. Nuestro servicio de software a medida incluye tambi\u00e9n eLearning a la medida, para ayudarte a configurar lo que sea que necesites.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66b88544 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"66b88544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399671_SEO.png\" class=\"attachment-full size-full wp-image-31\" alt=\"Con el Software ERP a Medida de The Cloud Group podr\u00e1s trabajar desde cualquier lugar.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399671_SEO.png 128w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399671_SEO-66x66.png 66w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Aprendizaje Interactivo<\/div><p class=\"elementor-image-box-description\">Sabemos que se aprende m\u00e1s f\u00e1cil en la pr\u00e1ctica que conociendo solo la teor\u00eda. Es por ello que nuestras plataformas de eLearning profesionales ofrecen la posibilidad de crear y construir una experiencia interactiva para que el aprendizaje ocurra m\u00e1s f\u00e1cil, fluya m\u00e1s y sea m\u00e1s duradero. \u00a1No nos gustan las clases aburridas!\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37928810\" data-id=\"37928810\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-224df3cf elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"224df3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design.png\" class=\"attachment-full size-full wp-image-33\" alt=\"Con el Software ERP a Medida de The Cloud Group obtendr\u00e1s un dise\u00f1o visualmente amigable.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design.png 512w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-500x500.png 500w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-100x100.png 100w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-416x416.png 416w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-300x300.png 300w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-150x150.png 150w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-66x66.png 66w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-200x200.png 200w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399594_Web_Design-400x400.png 400w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Aprovecha Internet<\/h3><p class=\"elementor-image-box-description\">Hoy en el d\u00eda eLearning est\u00e1 disponible en diversas plataformas y podremos ayudarte a configurar la tuya a fin de que la posibilidad de ense\u00f1ar a distancia sea posible para ti. Cada vez est\u00e1n m\u00e1s en boga los cursos y clases en l\u00ednea y podemos apoyarte en lograr que t\u00fa tambi\u00e9n te puedas unir a la tendencia.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b488e2e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"6b488e2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399656_Branding.png\" class=\"attachment-full size-full wp-image-35\" alt=\"Con el Software ERP a Medida de The Cloud Group obtendr\u00e1s un sistema totalmente intuitivo.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399656_Branding.png 128w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399656_Branding-66x66.png 66w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">F\u00e1cil de Utilizar<\/div><p class=\"elementor-image-box-description\">No necesitas saber programar y leer c\u00f3digos. Tampoco necesitas saber dise\u00f1ar. Todo esto nosotros lo hacemos por ti. Nos enfocaremos en plataformas eLearning profesionales que sean f\u00e1ciles de utilizar, tanto para los estudiantes, como para los profesores y cualquier otra personas que est\u00e9 involucrada con la experiencia.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd715f4 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"7cd715f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399667_Newsletter.png\" class=\"attachment-full size-full wp-image-34\" alt=\"Con el Software ERP a Medida de The Cloud Group mejorar\u00e1s notablemente tu comunicaci\u00f3n.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399667_Newsletter.png 128w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399667_Newsletter-100x100.png 100w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/1470399667_Newsletter-66x66.png 66w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Ofrece Libertad<\/div><p class=\"elementor-image-box-description\">El eLearning es sin\u00f3nimo de libertad porque les permite a los estudiantes, dependiendo del tipo de curso, taller o profesi\u00f3n que est\u00e9n realizando en la plataforma, decidir cu\u00e1ndo y c\u00f3mo van a aprender. Adem\u00e1s, los profesores tambi\u00e9n podr\u00e1n decidir c\u00f3mo quieren ense\u00f1ar y a trav\u00e9s de qu\u00e9 herramientas.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a354ba2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4a354ba2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/thecloud.group\/contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00bfListo para comenzar?<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62418f03 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"62418f03\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7305c5de\" data-id=\"7305c5de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6faece8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6faece8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34063fde elementor-widget elementor-widget-heading\" data-id=\"34063fde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-large\">INCREMENTA LA INTERACCI\u00d3N<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dc81696 elementor-widget elementor-widget-text-editor\" data-id=\"2dc81696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las plataformas de eLearning profesionales o aprendizaje online permiten una forma de ense\u00f1ar y aprender <b>completamente interactiva.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/p><p>Desde contenido multimedia hasta elementos que incentivan la participaci\u00f3n y mucho m\u00e1s, todo<b> enfocado a lograr una mejor experiencia.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bdcee6e elementor-widget elementor-widget-heading\" data-id=\"2bdcee6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-large\"><a href=\"https:\/\/thecloud.group\/tendencias-de-diseno-web-2020\/\">LEE SOBRE T\u00c9CNICAS DE DISE\u00d1O WEB 2020<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ef3dc6 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"53ef3dc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3fecc2d8\" data-id=\"3fecc2d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d189dc7 elementor-widget elementor-widget-image\" data-id=\"6d189dc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/eople.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Imagen Dise\u00f1o de eLearning Profesionales.\" data-elementor-lightbox-description=\"Con el dise\u00f1o de eLearning Profesionales de The Cloud Group podr\u00e1s obtener plataformas totalmente interactivas enfocadas en lograr una mejor experiencia.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjgyLCJ1cmwiOiJodHRwczpcL1wvdGhlY2xvdWQuZ3JvdXBcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzA1XC9lb3BsZS5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/eople-300x170.png\" class=\"attachment-medium size-medium wp-image-682\" alt=\"Con el dise\u00f1o de eLearning Profesionales de The Cloud Group podr\u00e1s obtener plataformas totalmente interactivas enfocadas en lograr una mejor experiencia.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/eople-300x170.png 300w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/eople-200x113.png 200w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/eople.png 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dfb7b9c elementor-section-height-min-height elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3dfb7b9c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a7b1721\" data-id=\"7a7b1721\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51177da6 elementor-widget elementor-widget-image\" data-id=\"51177da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/ahorroCostes.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Imagen Creaci\u00f3n de Landing Pages Profesionales.\" data-elementor-lightbox-description=\"Con la creaci\u00f3n de Landing Pages Profesionales de The Cloud Group obtendr\u00e1s una de las opciones m\u00e1s econ\u00f3micas para cerrar multitud de ventas en un corto plazo.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTQwLCJ1cmwiOiJodHRwczpcL1wvdGhlY2xvdWQuZ3JvdXBcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzA1XC9haG9ycm9Db3N0ZXMuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"316\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/ahorroCostes.jpg\" class=\"attachment-full size-full wp-image-940\" alt=\"Con la creaci\u00f3n de Landing Pages Profesionales de The Cloud Group obtendr\u00e1s una de las opciones m\u00e1s econ\u00f3micas para cerrar multitud de ventas en un corto plazo.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/ahorroCostes.jpg 350w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/ahorroCostes-324x293.jpg 324w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/ahorroCostes-300x271.jpg 300w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/ahorroCostes-200x181.jpg 200w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5cd5b3a4\" data-id=\"5cd5b3a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-595fa001 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"595fa001\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c771e69 elementor-widget elementor-widget-heading\" data-id=\"2c771e69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">DISMINUYE LOS COSTES<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-516afa89 elementor-widget elementor-widget-text-editor\" data-id=\"516afa89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ense\u00f1a a miles de estudiantes <b>de forma m\u00e1s f\u00e1cil y econ\u00f3mica<\/b>. Costos por alquilar salas de conferencia, personal, snacks, traslado, equipos y mucho m\u00e1s se reducen al m\u00ednimo gracias a las herramientas que nos ofrecen los eLearnings profesionales.<\/p><p>S\u00fabete al tren del Siglo XXI en donde <b>el aprendizaje a distancia ya es una realidad.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11819f40 elementor-widget elementor-widget-heading\" data-id=\"11819f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-large\"><a href=\"https:\/\/thecloud.group\/diseno-web-profesional-madrid\/\" target=\"_blank\">LA IMPORTANCIA DE UN BUEN DISE\u00d1O<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4618d4 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a4618d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b372f20\" data-id=\"7b372f20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71916bc8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"71916bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58055df1 elementor-widget elementor-widget-heading\" data-id=\"58055df1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">CUANDO Y DONDE QUIERAS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c866bc3 elementor-widget elementor-widget-text-editor\" data-id=\"3c866bc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-kerning: none;\">Las plataformas de eLearning profesionales pueden ofrecer clases en vivo, pero para todo lo dem\u00e1s, tanto los profesores como los estudiantes pueden decidir <b>c\u00f3mo, cu\u00e1ndo y d\u00f3nde van a ense\u00f1ar o aprender.\u00a0<\/b><\/span><\/p><p><span style=\"font-kerning: none;\">\u00a1Decide tu futuro hoy a trav\u00e9s de las bondades que ofrecen las plataformas eLearning profesionales!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44af04e8 elementor-widget elementor-widget-heading\" data-id=\"44af04e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-medium\"><a href=\"https:\/\/thecloud.group\/impacto-buen-diseno-para-tu-empresa\">IMPACTO DEL BUEN DISE\u00d1O EN TU NEGOCIO<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c9a50a elementor-widget elementor-widget-spacer\" data-id=\"73c9a50a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23ab06c\" data-id=\"23ab06c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-604b511 elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"604b511\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"280\" src=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/GLOBALIZACION.jpg\" class=\"attachment-full size-full wp-image-913\" alt=\"Con el Dise\u00f1o de Tiendas Online de The Cloud Group podr\u00e1s acceder a tu tienda online desde donde sea las 24 horas al d\u00eda, los 7 d\u00edas de la semana.\" srcset=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/GLOBALIZACION.jpg 300w, https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/GLOBALIZACION-200x187.jpg 200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-629da262 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"629da262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/thecloud.group\/contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HABLA CON UN EXPERTO EN DISE\u00d1O DE ELEARNING PROFESIONALES HOY<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10dfaf09 elementor-section-content-middle elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"10dfaf09\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b1c0850\" data-id=\"5b1c0850\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27c06fe6 elementor-widget elementor-widget-text-editor\" data-id=\"27c06fe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Queremos ayudarte a hacer realidad todos tus proyectos y si un eLearning profesional es uno de ellos, <strong>puedes contar con nosotros.<\/strong><\/p><p>Nos preocupamos mucho en The Cloud Group por mejorar constantemente y queremos hacer lo mismo en equipo contigo. Es por ello que estamos m\u00e1s que preparados para ser tu <strong>aliado en tu proyecto de eLearning.<\/strong> \u00bfEst\u00e1s listo? \u00a1Nosotros s\u00ed!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14d2136c\" data-id=\"14d2136c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bcd46d0 elementor-widget elementor-widget-heading\" data-id=\"3bcd46d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">\"El competidor a ser temido no es el que nunca se preocupa por ti, sino el que contin\u00faa haciendo que su negocio sea mejor todo el tiempo.\"<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-558f255d elementor-widget elementor-widget-heading\" data-id=\"558f255d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">STEVE JOBS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DISE\u00d1O DE E-LEARNINGS PROFESIONALES Con nuestros servicios de eLearning profesionales podr\u00e1s ofrecerle a tu equipo o a tus estudiantes un espacio para que se sigan formando a distancia. Clientes Capacitaci\u00f3n Flexible Nuestra empresa de desarrollo de software te ayudar\u00e1 a crear esa plataforma de eLearning para la ense\u00f1anza a distancia que tanto est\u00e1s buscando. A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":664,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-978","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>eLearning Profesionales: Dsie\u00f1o a medida | The Cloud Group<\/title>\n<meta name=\"description\" content=\"The Cloud Group ofrece el dise\u00f1o de eLearning Profesionales totalmente personalizadas. Descubre nuestros planes y apuesta por la formaci\u00f3n a distancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thecloud.group\/pt\/profissionais-de-elearning\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eLearning Profesionales\" \/>\n<meta property=\"og:description\" content=\"Desarrollamos software a medida, automatizaci\u00f3n empresarial e inteligencia artificial para empresas. Creamos ERP, CRM, aplicaciones web y m\u00f3viles adaptadas a cada negocio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thecloud.group\/pt\/profissionais-de-elearning\/\" \/>\n<meta property=\"og:site_name\" content=\"The Cloud Group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/thecloudgroupglobal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-28T16:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/seotestingbackground.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@thecloudgroup\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/\",\"url\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/\",\"name\":\"eLearning Profesionales: Dsie\u00f1o a medida | The Cloud Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thecloud.group\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thecloud.group\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/seotestingbackground.jpg\",\"datePublished\":\"2020-05-20T17:38:01+00:00\",\"dateModified\":\"2023-07-28T16:37:03+00:00\",\"description\":\"The Cloud Group ofrece el dise\u00f1o de eLearning Profesionales totalmente personalizadas. Descubre nuestros planes y apuesta por la formaci\u00f3n a distancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thecloud.group\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/seotestingbackground.jpg\",\"contentUrl\":\"https:\\\/\\\/thecloud.group\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/seotestingbackground.jpg\",\"width\":900,\"height\":600,\"caption\":\"En The Cloud Group estamos especializados en el dise\u00f1o de P\u00e1ginas Web Profesionales, eCommerce y mucho m\u00e1s. Descubre todos nuestros paquetes.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thecloud.group\\\/elearning-profesionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thecloud.group\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eLearning Profesionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thecloud.group\\\/#website\",\"url\":\"https:\\\/\\\/thecloud.group\\\/\",\"name\":\"The Cloud Group\",\"description\":\"Empresa especializada en desarrollo de software a medida, automatizaci\u00f3n empresarial e inteligencia artificial para empresas.\",\"publisher\":{\"@id\":\"https:\\\/\\\/thecloud.group\\\/#organization\"},\"alternateName\":\"TCG Software\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thecloud.group\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thecloud.group\\\/#organization\",\"name\":\"The Cloud Group\",\"alternateName\":\"TCG\",\"url\":\"https:\\\/\\\/thecloud.group\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/thecloud.group\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thecloud.group\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logoSmallFirmaCorreo.png\",\"contentUrl\":\"https:\\\/\\\/thecloud.group\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logoSmallFirmaCorreo.png\",\"width\":300,\"height\":190,\"caption\":\"The Cloud Group\"},\"image\":{\"@id\":\"https:\\\/\\\/thecloud.group\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thecloudgroupglobal\",\"https:\\\/\\\/x.com\\\/thecloudgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/the-cloud-group\",\"https:\\\/\\\/www.instagram.com\\\/thecloudgroupglobal\",\"https:\\\/\\\/www.youtube.com\\\/@TheCloudGroup\"],\"description\":\"The Cloud Group es una empresa internacional especializada en desarrollo de software a medida, automatizaci\u00f3n empresarial, inteligencia artificial, ERP, CRM, aplicaciones web y m\u00f3viles y transformaci\u00f3n digital. Ayudamos a empresas a optimizar procesos, reducir costos y acelerar su crecimiento mediante soluciones tecnol\u00f3gicas personalizadas.\",\"email\":\"paula.franco@thecloud.group\",\"telephone\":\"3042544988\",\"legalName\":\"THE CLOUD COLOMBIA SAS\",\"vatID\":\"902084280\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Profissionais de eLearning: Design Personalizado | The Cloud Group","description":"O Cloud Group oferece projetos de eLearning profissionais totalmente personalizados. Descubra nossos planos e invista em educa\u00e7\u00e3o a dist\u00e2ncia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thecloud.group\/pt\/profissionais-de-elearning\/","og_locale":"pt_PT","og_type":"article","og_title":"eLearning Profesionales","og_description":"Desarrollamos software a medida, automatizaci\u00f3n empresarial e inteligencia artificial para empresas. Creamos ERP, CRM, aplicaciones web y m\u00f3viles adaptadas a cada negocio.","og_url":"https:\/\/thecloud.group\/pt\/profissionais-de-elearning\/","og_site_name":"The Cloud Group","article_publisher":"https:\/\/www.facebook.com\/thecloudgroupglobal","article_modified_time":"2023-07-28T16:37:03+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/seotestingbackground.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@thecloudgroup","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thecloud.group\/elearning-profesionales\/","url":"https:\/\/thecloud.group\/elearning-profesionales\/","name":"Profissionais de eLearning: Design Personalizado | The Cloud Group","isPartOf":{"@id":"https:\/\/thecloud.group\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thecloud.group\/elearning-profesionales\/#primaryimage"},"image":{"@id":"https:\/\/thecloud.group\/elearning-profesionales\/#primaryimage"},"thumbnailUrl":"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/seotestingbackground.jpg","datePublished":"2020-05-20T17:38:01+00:00","dateModified":"2023-07-28T16:37:03+00:00","description":"O Cloud Group oferece projetos de eLearning profissionais totalmente personalizados. Descubra nossos planos e invista em educa\u00e7\u00e3o a dist\u00e2ncia.","breadcrumb":{"@id":"https:\/\/thecloud.group\/elearning-profesionales\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thecloud.group\/elearning-profesionales\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/thecloud.group\/elearning-profesionales\/#primaryimage","url":"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/seotestingbackground.jpg","contentUrl":"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/seotestingbackground.jpg","width":900,"height":600,"caption":"En The Cloud Group estamos especializados en el dise\u00f1o de P\u00e1ginas Web Profesionales, eCommerce y mucho m\u00e1s. Descubre todos nuestros paquetes."},{"@type":"BreadcrumbList","@id":"https:\/\/thecloud.group\/elearning-profesionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thecloud.group\/"},{"@type":"ListItem","position":2,"name":"eLearning Profesionales"}]},{"@type":"WebSite","@id":"https:\/\/thecloud.group\/#website","url":"https:\/\/thecloud.group\/","name":"O Grupo Cloud","description":"Empresa especializada em desenvolvimento de software personalizado, automa\u00e7\u00e3o de neg\u00f3cios e intelig\u00eancia artificial para empresas.","publisher":{"@id":"https:\/\/thecloud.group\/#organization"},"alternateName":"TCG Software","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thecloud.group\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/thecloud.group\/#organization","name":"O Grupo Cloud","alternateName":"TCG","url":"https:\/\/thecloud.group\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/thecloud.group\/#\/schema\/logo\/image\/","url":"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/logoSmallFirmaCorreo.png","contentUrl":"https:\/\/thecloud.group\/wp-content\/uploads\/2020\/05\/logoSmallFirmaCorreo.png","width":300,"height":190,"caption":"The Cloud Group"},"image":{"@id":"https:\/\/thecloud.group\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thecloudgroupglobal","https:\/\/x.com\/thecloudgroup","https:\/\/www.linkedin.com\/company\/the-cloud-group","https:\/\/www.instagram.com\/thecloudgroupglobal","https:\/\/www.youtube.com\/@TheCloudGroup"],"description":"A Cloud Group \u00e9 uma empresa internacional especializada em desenvolvimento de software personalizado, automa\u00e7\u00e3o de neg\u00f3cios, intelig\u00eancia artificial, ERP, CRM, aplicativos web e mobile e transforma\u00e7\u00e3o digital. Ajudamos empresas a otimizar processos, reduzir custos e acelerar seu crescimento por meio de solu\u00e7\u00f5es tecnol\u00f3gicas personalizadas.","email":"paula.franco@thecloud.group","telephone":"3042544988","legalName":"THE CLOUD COLOMBIA SAS","vatID":"902084280"}]}},"_links":{"self":[{"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/pages\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/comments?post=978"}],"version-history":[{"count":14,"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/pages\/978\/revisions"}],"predecessor-version":[{"id":25304,"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/pages\/978\/revisions\/25304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/media\/664"}],"wp:attachment":[{"href":"https:\/\/thecloud.group\/pt\/wp-json\/wp\/v2\/media?parent=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}